{"id":28725,"date":"2026-02-11T16:25:55","date_gmt":"2026-02-11T15:25:55","guid":{"rendered":"https:\/\/dach.tdsynnex.com\/blog\/de\/?post_type=news&#038;p=28725"},"modified":"2026-05-13T16:30:21","modified_gmt":"2026-05-13T14:30:21","slug":"cyberark","status":"publish","type":"news","link":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/","title":{"rendered":"Updates zur CyberArk Akquise"},"author":61,"featured_media":1599,"template":"","flags":[],"hersteller":[371],"themen":[129],"class_list":["post-28725","news","type-news","status-publish","has-post-thumbnail","hentry","hersteller-palo-alto","themen-security"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Updates zur CyberArk Akquise - TD SYNNEX Blog DE<\/title>\n<meta name=\"description\" content=\"% TD SYNNEX, Ihr Palo Alto Networks Distributor, informiert Sie auf dieser Seite regelm\u00e4\u00dfig \u00fcber den aktuellen Stand der Akquise von CyberArk sowie \u00fcber alle relevanten Entwicklungen, Hintergr\u00fcnde und Auswirkungen f\u00fcr unsere Partner. Updates zur CyberArk Akquise\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Updates zur CyberArk Akquise\" \/>\n<meta property=\"og:description\" content=\"TD SYNNEX, Ihr Palo Alto Networks Distributor, informiert Sie auf dieser Seite regelm\u00e4\u00dfig \u00fcber den aktuellen Stand der Akquise von CyberArk sowie \u00fcber alle relevanten Entwicklungen, Hintergr\u00fcnde und Auswirkungen f\u00fcr unsere Partner.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/\" \/>\n<meta property=\"og:site_name\" content=\"TD SYNNEX Blog DE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/AdobeStock_173755013-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/\",\"name\":\"Updates zur CyberArk Akquise - TD SYNNEX Blog DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/AdobeStock_173755013-scaled.jpeg\",\"datePublished\":\"2026-02-11T15:25:55+00:00\",\"dateModified\":\"2026-05-13T14:30:21+00:00\",\"description\":\"% TD SYNNEX, Ihr Palo Alto Networks Distributor, informiert Sie auf dieser Seite regelm\u00e4\u00dfig \u00fcber den aktuellen Stand der Akquise von CyberArk sowie \u00fcber alle relevanten Entwicklungen, Hintergr\u00fcnde und Auswirkungen f\u00fcr unsere Partner. Updates zur CyberArk Akquise\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/AdobeStock_173755013-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/AdobeStock_173755013-scaled.jpeg\",\"width\":2560,\"height\":1661},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/cyberark\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Updates zur CyberArk Akquise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/\",\"name\":\"TD SYNNEX\",\"description\":\"Ihr Content-Hub f\u00fcr den IT-Channel\",\"publisher\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#organization\"},\"alternateName\":\"TD SYNNEX\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#organization\",\"name\":\"TD SYNNEX\",\"alternateName\":\"TD SYNNEX\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/cropped-TD-SYNNEX_fav.png\",\"contentUrl\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/cropped-TD-SYNNEX_fav.png\",\"width\":512,\"height\":512,\"caption\":\"TD SYNNEX\"},\"image\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Updates zur CyberArk Akquise - TD SYNNEX Blog DE","description":"% TD SYNNEX, Ihr Palo Alto Networks Distributor, informiert Sie auf dieser Seite regelm\u00e4\u00dfig \u00fcber den aktuellen Stand der Akquise von CyberArk sowie \u00fcber alle relevanten Entwicklungen, Hintergr\u00fcnde und Auswirkungen f\u00fcr unsere Partner. Updates zur CyberArk Akquise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/","og_locale":"de_DE","og_type":"article","og_title":"Updates zur CyberArk Akquise","og_description":"TD SYNNEX, Ihr Palo Alto Networks Distributor, informiert Sie auf dieser Seite regelm\u00e4\u00dfig \u00fcber den aktuellen Stand der Akquise von CyberArk sowie \u00fcber alle relevanten Entwicklungen, Hintergr\u00fcnde und Auswirkungen f\u00fcr unsere Partner.","og_url":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/","og_site_name":"TD SYNNEX Blog DE","article_modified_time":"2026-05-13T14:30:21+00:00","og_image":[{"width":2560,"height":1661,"url":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/AdobeStock_173755013-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/","name":"Updates zur CyberArk Akquise - TD SYNNEX Blog DE","isPartOf":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/#primaryimage"},"image":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/#primaryimage"},"thumbnailUrl":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/AdobeStock_173755013-scaled.jpeg","datePublished":"2026-02-11T15:25:55+00:00","dateModified":"2026-05-13T14:30:21+00:00","description":"% TD SYNNEX, Ihr Palo Alto Networks Distributor, informiert Sie auf dieser Seite regelm\u00e4\u00dfig \u00fcber den aktuellen Stand der Akquise von CyberArk sowie \u00fcber alle relevanten Entwicklungen, Hintergr\u00fcnde und Auswirkungen f\u00fcr unsere Partner. Updates zur CyberArk Akquise","breadcrumb":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/#primaryimage","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/AdobeStock_173755013-scaled.jpeg","contentUrl":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/AdobeStock_173755013-scaled.jpeg","width":2560,"height":1661},{"@type":"BreadcrumbList","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/cyberark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dach.tdsynnex.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Updates zur CyberArk Akquise"}]},{"@type":"WebSite","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#website","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/","name":"TD SYNNEX","description":"Ihr Content-Hub f\u00fcr den IT-Channel","publisher":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#organization"},"alternateName":"TD SYNNEX","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dach.tdsynnex.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#organization","name":"TD SYNNEX","alternateName":"TD SYNNEX","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/01\/cropped-TD-SYNNEX_fav.png","contentUrl":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/01\/cropped-TD-SYNNEX_fav.png","width":512,"height":512,"caption":"TD SYNNEX"},"image":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":true,"date":"2029-02-11 15:33:26","action":"change-status","newStatus":"draft","terms":[0],"taxonomy":"flags","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news\/28725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/users\/61"}],"version-history":[{"count":5,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news\/28725\/revisions"}],"predecessor-version":[{"id":30678,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news\/28725\/revisions\/30678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/media\/1599"}],"wp:attachment":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=28725"}],"wp:term":[{"taxonomy":"flags","embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/flags?post=28725"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/hersteller?post=28725"},{"taxonomy":"themen","embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/themen?post=28725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}