{"id":29763,"date":"2026-03-30T10:41:17","date_gmt":"2026-03-30T08:41:17","guid":{"rendered":"https:\/\/dach.tdsynnex.com\/blog\/de\/?post_type=news&#038;p=29763"},"modified":"2026-04-20T09:53:59","modified_gmt":"2026-04-20T07:53:59","slug":"neu-im-cyber-resilienz-portfolio-object-first","status":"publish","type":"news","link":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/","title":{"rendered":"Neu im Cyber-Resilienz Portfolio: Object First \u202f"},"author":100,"featured_media":29764,"template":"","flags":[],"hersteller":[],"themen":[129,126],"class_list":["post-29763","news","type-news","status-publish","has-post-thumbnail","hentry","themen-security","themen-unternehmensmeldungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Neu im Cyber-Resilienz Portfolio: Object First \u202f - TD SYNNEX Blog DE<\/title>\n<meta name=\"description\" content=\"TD SYNNEX erweitert ihr Cyber-Resilienz Portfolio durch eine Distributionspartnerschaft mit Object First \u202f\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neu im Cyber-Resilienz Portfolio: Object First \u202f\" \/>\n<meta property=\"og:description\" content=\"TD SYNNEX erweitert ihr Cyber-Resilienz Portfolio durch eine Distributionspartnerschaft mit Object First \u202f\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/\" \/>\n<meta property=\"og:site_name\" content=\"TD SYNNEX Blog DE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T07:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Object-First-Logo-Primary.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"951\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/\",\"name\":\"Neu im Cyber-Resilienz Portfolio: Object First \u202f - TD SYNNEX Blog DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Object-First-Logo-Primary.jpg\",\"datePublished\":\"2026-03-30T08:41:17+00:00\",\"dateModified\":\"2026-04-20T07:53:59+00:00\",\"description\":\"TD SYNNEX erweitert ihr Cyber-Resilienz Portfolio durch eine Distributionspartnerschaft mit Object First \u202f\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Object-First-Logo-Primary.jpg\",\"contentUrl\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/Object-First-Logo-Primary.jpg\",\"width\":951,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/news\\\/neu-im-cyber-resilienz-portfolio-object-first\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neu im Cyber-Resilienz Portfolio: Object First \u202f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/\",\"name\":\"TD SYNNEX\",\"description\":\"Ihr Content-Hub f\u00fcr den IT-Channel\",\"publisher\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#organization\"},\"alternateName\":\"TD SYNNEX\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#organization\",\"name\":\"TD SYNNEX\",\"alternateName\":\"TD SYNNEX\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/cropped-TD-SYNNEX_fav.png\",\"contentUrl\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/cropped-TD-SYNNEX_fav.png\",\"width\":512,\"height\":512,\"caption\":\"TD SYNNEX\"},\"image\":{\"@id\":\"https:\\\/\\\/dach.tdsynnex.com\\\/blog\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Neu im Cyber-Resilienz Portfolio: Object First \u202f - TD SYNNEX Blog DE","description":"TD SYNNEX erweitert ihr Cyber-Resilienz Portfolio durch eine Distributionspartnerschaft mit Object First \u202f","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/","og_locale":"de_DE","og_type":"article","og_title":"Neu im Cyber-Resilienz Portfolio: Object First \u202f","og_description":"TD SYNNEX erweitert ihr Cyber-Resilienz Portfolio durch eine Distributionspartnerschaft mit Object First \u202f","og_url":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/","og_site_name":"TD SYNNEX Blog DE","article_modified_time":"2026-04-20T07:53:59+00:00","og_image":[{"width":951,"height":500,"url":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Object-First-Logo-Primary.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/","name":"Neu im Cyber-Resilienz Portfolio: Object First \u202f - TD SYNNEX Blog DE","isPartOf":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/#primaryimage"},"image":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/#primaryimage"},"thumbnailUrl":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Object-First-Logo-Primary.jpg","datePublished":"2026-03-30T08:41:17+00:00","dateModified":"2026-04-20T07:53:59+00:00","description":"TD SYNNEX erweitert ihr Cyber-Resilienz Portfolio durch eine Distributionspartnerschaft mit Object First \u202f","breadcrumb":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/#primaryimage","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Object-First-Logo-Primary.jpg","contentUrl":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/Object-First-Logo-Primary.jpg","width":951,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/news\/neu-im-cyber-resilienz-portfolio-object-first\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dach.tdsynnex.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Neu im Cyber-Resilienz Portfolio: Object First \u202f"}]},{"@type":"WebSite","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#website","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/","name":"TD SYNNEX","description":"Ihr Content-Hub f\u00fcr den IT-Channel","publisher":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#organization"},"alternateName":"TD SYNNEX","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dach.tdsynnex.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#organization","name":"TD SYNNEX","alternateName":"TD SYNNEX","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/01\/cropped-TD-SYNNEX_fav.png","contentUrl":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-content\/uploads\/sites\/2\/2023\/01\/cropped-TD-SYNNEX_fav.png","width":512,"height":512,"caption":"TD SYNNEX"},"image":{"@id":"https:\/\/dach.tdsynnex.com\/blog\/de\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":true,"date":"2029-03-30 10:34:07","action":"change-status","newStatus":"draft","terms":[0],"taxonomy":"flags","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news\/29763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/users\/100"}],"version-history":[{"count":1,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news\/29763\/revisions"}],"predecessor-version":[{"id":29766,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/news\/29763\/revisions\/29766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/media\/29764"}],"wp:attachment":[{"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=29763"}],"wp:term":[{"taxonomy":"flags","embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/flags?post=29763"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/hersteller?post=29763"},{"taxonomy":"themen","embeddable":true,"href":"https:\/\/dach.tdsynnex.com\/blog\/de\/wp-json\/wp\/v2\/themen?post=29763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}